{"id":277,"date":"2016-05-12T22:30:53","date_gmt":"2016-05-12T22:30:53","guid":{"rendered":"https:\/\/mitologiaegipcia.wordpress.com\/?p=277"},"modified":"2016-05-12T22:30:53","modified_gmt":"2016-05-12T22:30:53","slug":"esfinge","status":"publish","type":"post","link":"https:\/\/eloaelo.com\/mitoegip\/2016\/05\/12\/esfinge\/","title":{"rendered":"Esfinge"},"content":{"rendered":"<p>Pode ser encontrada nas cartas:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-286\" src=\"https:\/\/eloaelo.com\/mitoegip\/wp-content\/uploads\/2016\/05\/iarc101.jpg\" alt=\"IArc10\" width=\"111\" height=\"216\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-285\" src=\"https:\/\/eloaelo.com\/mitoegip\/wp-content\/uploads\/2016\/05\/iarc071.jpg\" alt=\"IArc07\" width=\"112\" height=\"216\" \/><\/p>\n<ul>\n<li>Um le\u00e3o com cabe\u00e7a humana, as vezes com asas de falc\u00e3o. Existem diversas especula\u00e7\u00f5es sobre sua origem e significado.<\/li>\n<li>Pode ser vista como a cabe\u00e7a de fara\u00f3 no corpo de le\u00e3o, o que indica a for\u00e7a e a supremacia do fara\u00f3.<\/li>\n<li>A esfinge com cabe\u00e7a de Fara\u00f3 tamb\u00e9m simboliza a divindade atribu\u00edda aos Reis eg\u00edpcios. Pois, a metamorfose de humano para animal, como as representa\u00e7\u00f5es de humanos com corpo ou cabe\u00e7a de animal, eram caracter\u00edsticas dos deuses.<\/li>\n<li>Ela tamb\u00e9m pode ser vista como a intelig\u00eancia humana que nos potencializa a superioridade sobre as feras selvagens, a intelig\u00eancia nos faz mais fortes do que \u201cO rei da selva\u201d o le\u00e3o.<\/li>\n<li>Nos contos de Atom, dizem que Atom era o deus criador e que todo o mundo f\u00edsico surgiu da massa primordial de Atom, que veio das aguas primordiais. O le\u00e3o foi o primeiro animal a sair da massa primordial. Atom era as vezes denotado como o le\u00e3o. (Winston, n.d.)<\/li>\n<li>Esfinges eram postas em frente de templos, t\u00famulos e reinos como prote\u00e7\u00e3o.<\/li>\n<li>Esfinges tamb\u00e9m s\u00e3o encontradas em outras culturas al\u00e9m da eg\u00edpcia, possivelmente derivando dela, um exemplo disso \u00e9 no mito grego sobre a esfinge alada de Tebas. A esfinge aterrorizou o povo exigindo a resposta para uma charada que aprendeu com as Musas. \u201cQue criatura pela manh\u00e3 tem quatro p\u00e9s, ao meio-dia tem dois, e \u00e0 tarde tem tr\u00eas?\u201d Ela devorava um homem de cada vez que respondia o enigma incorretamente. At\u00e9 que \u00c9dipo deu a resposta certa: O Homem, que engatinha de quatro na inf\u00e2ncia, anda de dois p\u00e9s quando cultiva, e apoia em sua muleta na velhice. Ao ouvir a resposta correta a esfinge se suicidou, deixando os cidad\u00e3os de Tebas em paz. (Britannica, 2015)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>No tarot significa:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>A necessidade da evolu\u00e7\u00e3o, \u00e9 o s\u00edmbolo do homem perfeito. Composto de uma parte humana de quatro animais: o touro, o le\u00e3o, a \u00e1guia e o drag\u00e3o. O s\u00edmbolo unifica, mesmo dentro da heterogeneidade, os quatro elementos e a quintess\u00eancia.<\/li>\n<li>O poder da sabedoria versus for\u00e7a f\u00edsica.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pode ser encontrada nas cartas: Um le\u00e3o com cabe\u00e7a humana, as vezes com asas de falc\u00e3o. Existem diversas especula\u00e7\u00f5es sobre sua origem e significado. Pode ser vista como a cabe\u00e7a de fara\u00f3 no corpo de le\u00e3o, o que indica a for\u00e7a e a supremacia do fara\u00f3. A esfinge com cabe\u00e7a de Fara\u00f3 tamb\u00e9m simboliza a &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/eloaelo.com\/mitoegip\/2016\/05\/12\/esfinge\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Esfinge&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":279,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,15],"tags":[],"class_list":["post-277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-e","category-simbolos"],"_links":{"self":[{"href":"https:\/\/eloaelo.com\/mitoegip\/wp-json\/wp\/v2\/posts\/277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eloaelo.com\/mitoegip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eloaelo.com\/mitoegip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eloaelo.com\/mitoegip\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eloaelo.com\/mitoegip\/wp-json\/wp\/v2\/comments?post=277"}],"version-history":[{"count":0,"href":"https:\/\/eloaelo.com\/mitoegip\/wp-json\/wp\/v2\/posts\/277\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eloaelo.com\/mitoegip\/wp-json\/wp\/v2\/media\/279"}],"wp:attachment":[{"href":"https:\/\/eloaelo.com\/mitoegip\/wp-json\/wp\/v2\/media?parent=277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eloaelo.com\/mitoegip\/wp-json\/wp\/v2\/categories?post=277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eloaelo.com\/mitoegip\/wp-json\/wp\/v2\/tags?post=277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}